{"id":9457,"date":"2026-05-15T02:46:27","date_gmt":"2026-05-15T06:46:27","guid":{"rendered":"https:\/\/www.materiauxmironplus.com\/produit\/ens-metrique-impact-1-2dr-14-mcx\/"},"modified":"2026-08-05T03:32:58","modified_gmt":"2026-08-05T07:32:58","slug":"ens-metrique-impact-1-2dr-14-mcx","status":"publish","type":"product","link":"https:\/\/www.materiauxmironplus.com\/boutique\/produit\/ens-metrique-impact-1-2dr-14-mcx\/","title":{"rendered":"ENS.METRIQUE IMPACT 1\/2DR 14 MCX"},"content":{"rendered":"<p>L&#8217;ensemble de 14 douilles m\u00e9triques \u00e0 6 pans MILWAUKEE SHOCKWAVE Impact Duty profondes avec prise de 1\/2 po permet d&#8217;effectuer les marques les plus \u00e9videntes et les plus durables et procure une r\u00e9sistance extr\u00eame aux impacts pour les utilisations \u00e0 couple \u00e9lev\u00e9.  Les marques estamp\u00e9es \u00e0 l&#8217;encre aident \u00e0 choisir facilement la bonne douille chaque fois Ces douilles Milwaukee sont con\u00e7ues \u00e0 partir d&#8217;acier forg\u00e9 \u00e0 haute r\u00e9sistance pour offrir un rendement optimis\u00e9 dans les applications de service intensif. La g\u00e9om\u00e9trie hexagonale qui ne glisse pas acc\u00e9l\u00e8re le processus d&#8217;arrondissement, alors que le concept \u00e0 deux orifices et la rainure de bague facilitent l&#8217;installation et la d\u00e9pose des douilles. Les bo\u00eetiers de rangement r\u00e9sistent aux chocs et s&#8217;embo\u00eetent pour faciliter l&#8217;empilage et le rangement Toutes les douilles SHOCKWAVE Impact Duty sont prot\u00e9g\u00e9es par une garantie \u00e0 vie et r\u00e9pondent aux normes ASME en vigueur dans l&#8217;industrie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ensemble de 14 douilles m\u00e9triques \u00e0 6 pans MILWAUKEE SHOCKWAVE Impact Duty profondes avec prise de 1\/2 po permet d&#8217;effectuer les marques les plus \u00e9videntes et les plus durables et procure une r\u00e9sistance extr\u00eame aux impacts pour les utilisations \u00e0 couple \u00e9lev\u00e9. Les marques estamp\u00e9es \u00e0 l&#8217;encre aident \u00e0 choisir facilement la bonne douille chaque [&hellip;]<\/p>\n","protected":false},"featured_media":21809,"template":"","meta":{"_mi_skip_tracking":false,"_themeisle_gutenberg_block_has_review":false},"miron":[],"product_cat":[240,97],"product_tag":[],"class_list":["post-9457","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-cliquet-ratchet-cle","product_cat-outil-manuel-milwaukee","wc-prl-cat-240-97","cf"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/product\/9457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/media\/21809"}],"wp:attachment":[{"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/media?parent=9457"}],"wp:term":[{"taxonomy":"miron","embeddable":true,"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/miron?post=9457"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/product_cat?post=9457"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.materiauxmironplus.com\/boutique\/wp-json\/wp\/v2\/product_tag?post=9457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}